{"id":285,"count":1,"description":"","link":"https:\/\/hopbettershoes.com\/id\/tag\/sepatu-kets-mode-putih\/","name":"white fashion sneakers","slug":"white-fashion-sneakers","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/hopbettershoes.com\/id\/wp-json\/wp\/v2\/tags\/285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hopbettershoes.com\/id\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/hopbettershoes.com\/id\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/hopbettershoes.com\/id\/wp-json\/wp\/v2\/posts?tags=285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}