{"id":309,"count":1,"description":"","link":"https:\/\/hopbettershoes.com\/ne\/tag\/\u092c\u093e\u0915\u094d\u0932\u094b-\u0938\u094b\u0932-\u0906\u0930\u094d\u091a-\u0938\u092a\u094b\u0930\u094d\u091f-\u091c\u0941\/","name":"Thick Sole Arch Support shoes","slug":"thick-sole-arch-support-shoes","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/hopbettershoes.com\/ne\/wp-json\/wp\/v2\/tags\/309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hopbettershoes.com\/ne\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/hopbettershoes.com\/ne\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/hopbettershoes.com\/ne\/wp-json\/wp\/v2\/posts?tags=309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}