{"id":356,"count":1,"description":"","link":"https:\/\/hopbettershoes.com\/vi\/tag\/low-top-shoes\/","name":"Low-top shoes","slug":"low-top-shoes","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/hopbettershoes.com\/vi\/wp-json\/wp\/v2\/tags\/356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hopbettershoes.com\/vi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/hopbettershoes.com\/vi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/hopbettershoes.com\/vi\/wp-json\/wp\/v2\/posts?tags=356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}